{"id":1644,"date":"2024-05-22T12:41:35","date_gmt":"2024-05-22T12:41:35","guid":{"rendered":"https:\/\/www2.zenato.it\/?p=1644"},"modified":"2026-01-21T17:10:01","modified_gmt":"2026-01-21T17:10:01","slug":"i-salotti-di-zenato-parola-di-vino","status":"publish","type":"post","link":"https:\/\/www.zenato.it\/en\/i-salotti-di-zenato-parola-di-vino\/","title":{"rendered":"I Salotti di Zenato &#8211; &#8220;PAROLA DI VINO&#8221;"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1644\" class=\"elementor elementor-1644\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a58e85d e-flex e-con-boxed e-con e-parent\" data-id=\"a58e85d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-778de7a elementor-widget elementor-widget-text-editor\" data-id=\"778de7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Abbiamo il piacere di annunciare la quinta edizione de<\/em><\/p><p><em><strong>&#8220;I Salotti di Zenato&#8221; \u2013 PAROLA DI VINO<\/strong><\/em><\/p><p><em>Conversando con\u00a0Nadia Zenato e\u00a0e Don Luca Passarini, responsabile della comunicazione della Diocesi di Verona.<\/em><br \/><br \/><b>Mercoled\u00ec 22 maggio 2024 ore 18:00<\/b><br \/>presso la nostra Tenuta S. Cristina a Peschiera del Garda<br \/><a href=\"https:\/\/maps.app.goo.gl\/ZW3pqEqGmRUuL4kRA\" target=\"_blank\" rel=\"noopener\">Trovaci su Maps<\/a><\/p><p><br \/>Seguir\u00e0 brindisi con i vini Zenato<br \/>RSVP:\u00a0<span id=\"cloak0ce185a6908d07da2dab9bdaac1adbee\"><a href=\"mailto:info@zenato.it\">info@zenato.it<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd6d18f elementor-widget elementor-widget-image\" data-id=\"fd6d18f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"859\" src=\"https:\/\/www.zenato.it\/wp-content\/uploads\/2024\/09\/Invito-Salotto_22_05_2024-954x1024.jpg\" class=\"attachment-large size-large wp-image-1647\" alt=\"\" srcset=\"https:\/\/www.zenato.it\/wp-content\/uploads\/2024\/09\/Invito-Salotto_22_05_2024-954x1024.jpg 954w, https:\/\/www.zenato.it\/wp-content\/uploads\/2024\/09\/Invito-Salotto_22_05_2024-280x300.jpg 280w, https:\/\/www.zenato.it\/wp-content\/uploads\/2024\/09\/Invito-Salotto_22_05_2024-768x824.jpg 768w, https:\/\/www.zenato.it\/wp-content\/uploads\/2024\/09\/Invito-Salotto_22_05_2024-1431x1536.jpg 1431w, https:\/\/www.zenato.it\/wp-content\/uploads\/2024\/09\/Invito-Salotto_22_05_2024-1908x2048.jpg 1908w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Abbiamo il piacere di annunciare la quinta edizione de &#8220;I Salotti di Zenato&#8221; \u2013 PAROLA DI VINO Conversando con\u00a0Nadia Zenato e\u00a0e Don Luca Passarini, responsabile della comunicazione della Diocesi di Verona. Mercoled\u00ec 22 maggio 2024 ore 18:00presso la nostra Tenuta S. Cristina a Peschiera del GardaTrovaci su Maps Seguir\u00e0 brindisi con i vini ZenatoRSVP:\u00a0info@zenato.it<\/p>\n","protected":false},"author":1,"featured_media":1645,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[233],"tags":[],"class_list":["post-1644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salotti-zenato"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/posts\/1644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/comments?post=1644"}],"version-history":[{"count":1,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/posts\/1644\/revisions"}],"predecessor-version":[{"id":12077,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/posts\/1644\/revisions\/12077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/media\/1645"}],"wp:attachment":[{"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/media?parent=1644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/categories?post=1644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/tags?post=1644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}