{"id":1753,"date":"2023-10-01T14:05:31","date_gmt":"2023-10-01T14:05:31","guid":{"rendered":"https:\/\/www2.zenato.it\/?p=1753"},"modified":"2026-01-21T17:10:12","modified_gmt":"2026-01-21T17:10:12","slug":"james-suckling-2023","status":"publish","type":"post","link":"https:\/\/www.zenato.it\/en\/james-suckling-2023\/","title":{"rendered":"James Suckling 2023"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1753\" class=\"elementor elementor-1753\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e43daa4 e-flex e-con-boxed e-con e-parent\" data-id=\"e43daa4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c00699 elementor-widget elementor-widget-text-editor\" data-id=\"1c00699\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019Amarone Riserva Sergio Zenato 2017<\/p><p>nella Top 100 World Wines 2023 di James Suckling<\/p><p>e nella Guida \u201cI 100 migliori vini e vignaioli d\u2019Italia\u201d a cura di Luciano Ferraro e James Suckling<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c02785a elementor-widget elementor-widget-text-editor\" data-id=\"c02785a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019<em>Amarone Riserva Sergio Zenato 2017<\/em>\u00a0\u00e8 stato selezionato con il punteggio di\u00a0<strong>98\/100\u00a0<\/strong>\u00a0tra i 100 migliori vini al mondo nella\u00a0<em>Top 100 World Wines 2023<\/em>\u00a0di James Suckling, uno dei critici pi\u00f9 influenti a livello internazionale.<\/p><p>39.000 vini recensiti da Suckling e dal team di sette degustatori\/redattori. Tra i 100 vini selezionati, 15 i vini italiani, di cui 11 toscani, 2 piemontesi, 1 siciliano e 1 veneto: l\u2019<em>Amarone Riserva Sergio Zenato 2017<\/em>.<\/p><p>In contemporanea, l\u2019uscita della Guida\u00a0<em>\u201cI 100 migliori vini e vignaioli d\u2019Italia\u201d, a cura di Luciano Ferraro e James Suckling<\/em>\u00a0ed edita dal Corriere della Sera, ha riconosciuto il ruolo della famiglia\u00a0<em>Zenato<\/em>\u00a0nel promuovere un\u2019enologia d\u2019eccellenza, affrontando i piccoli e grandi cambiamenti del momento, promuovendo anche interventi per una maggiore tutela ambientale nella produzione del vino.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f737c2d elementor-widget elementor-widget-image\" data-id=\"f737c2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.zenato.it\/wp-content\/uploads\/2024\/09\/Top_100_2023_ARiserva_2017_IG.jpg\" class=\"attachment-full size-full wp-image-1755\" alt=\"\" srcset=\"https:\/\/www.zenato.it\/wp-content\/uploads\/2024\/09\/Top_100_2023_ARiserva_2017_IG.jpg 1080w, https:\/\/www.zenato.it\/wp-content\/uploads\/2024\/09\/Top_100_2023_ARiserva_2017_IG-300x300.jpg 300w, https:\/\/www.zenato.it\/wp-content\/uploads\/2024\/09\/Top_100_2023_ARiserva_2017_IG-1024x1024.jpg 1024w, https:\/\/www.zenato.it\/wp-content\/uploads\/2024\/09\/Top_100_2023_ARiserva_2017_IG-150x150.jpg 150w, https:\/\/www.zenato.it\/wp-content\/uploads\/2024\/09\/Top_100_2023_ARiserva_2017_IG-768x768.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>L\u2019Amarone Riserva Sergio Zenato 2017 nella Top 100 World Wines 2023 di James Suckling e nella Guida \u201cI 100 migliori vini e vignaioli d\u2019Italia\u201d a cura di Luciano Ferraro e James Suckling L\u2019Amarone Riserva Sergio Zenato 2017\u00a0\u00e8 stato selezionato con il punteggio di\u00a098\/100\u00a0\u00a0tra i 100 migliori vini al mondo nella\u00a0Top 100 World Wines 2023\u00a0di James [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1733,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[236],"tags":[],"class_list":["post-1753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novita"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/posts\/1753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/comments?post=1753"}],"version-history":[{"count":1,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/posts\/1753\/revisions"}],"predecessor-version":[{"id":12090,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/posts\/1753\/revisions\/12090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/media\/1733"}],"wp:attachment":[{"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/media?parent=1753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/categories?post=1753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zenato.it\/en\/wp-json\/wp\/v2\/tags?post=1753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}